{"id":3791,"date":"2021-03-24T17:17:07","date_gmt":"2021-03-24T17:17:07","guid":{"rendered":"http:\/\/decormobel.com\/?page_id=3791"},"modified":"2022-05-13T17:00:03","modified_gmt":"2022-05-13T17:00:03","slug":"revestimientos","status":"publish","type":"page","link":"https:\/\/decormobel.com\/fr\/catalogue\/revetements\/","title":{"rendered":"Rev\u00eatements"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"3791\" class=\"elementor elementor-3791\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b7f4153 elementor-section-full_width elementor-section-content-middle elementor-section-height-default elementor-section-height-default gs-locked-section-no\" data-id=\"b7f4153\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-23ed955\" data-id=\"23ed955\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dc759c9 elementor-widget elementor-widget-spacer\" data-id=\"dc759c9\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.6.4 - 13-04-2022 *\/\n.e-container.e-container--row .elementor-spacer-inner{width:var(--spacer-size)}.e-container.e-container--column .elementor-spacer-inner,.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-849de6f\" data-id=\"849de6f\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e58602 elementor-widget elementor-widget-grada-section-title\" data-id=\"4e58602\" data-element_type=\"widget\" data-widget_type=\"grada-section-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t            <div class=\"gs-section-title-holder\">\n                \t\t\t\t    <span class=\"gs-section-tagline\">Parquets et c\u00e9ramiques<\/span>\n                                                    <div class=\"gs-section-title-inner\">\n\t                    \t\t                    <h1 class=\"gs-section-title\">Des sols pour tous les go\u00fbts<\/h1>\t                    \t\t\t                                        <div class=\"gs-section-title-content\">\n\t                            <p>Parquets, c\u00e9ramiques et gr\u00e8s naturels et synth\u00e9tiques de haute qualit\u00e9. Quoi que vous imaginiez, nous pouvons le r\u00e9aliser. Une collection des meilleures marques, ce qui permet une garantie \u00e0 vie du produit.<\/p>\n                            <\/div>\n                                            <\/div>\n                \t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-364da3f elementor-widget elementor-widget-button\" data-id=\"364da3f\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"http:\/\/decormobel.com\/fr\/contacto\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">viens nous rendre visite<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-65e3977 elementor-section-full_width elementor-section-height-default elementor-section-height-default gs-locked-section-no\" data-id=\"65e3977\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-27349b3\" data-id=\"27349b3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fec00f7 elementor-widget elementor-widget-grada-shop-products\" data-id=\"fec00f7\" data-element_type=\"widget\" data-settings=\"{&quot;products_carousel_items&quot;:4,&quot;products_carousel_margin&quot;:0,&quot;products_carousel_stage_padding&quot;:0}\" data-widget_type=\"grada-shop-products.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"gs-entries-wrapper gs-entries-filter gs-entries-style-classic-grid gs-woo-page\" data-entries-id=\"fec00f7\">\n\t\t\t\t\t\t\t\t                <div class=\"gs-woo-product-list gs-woo-product-list--classic-grid gs-overflow-hidden\">\n\t\t\t\t\t<div class=\"owl-carousel owl-theme\" id=\"gs-shop-carousel-6a04500960a6d\" data-animation=\"gsFadeIn\" data-wow=\"no\">\n\n\t\t\t\t\t<article class=\"product-holder wow gsFadeIn post-5786 product type-product status-publish has-post-thumbnail product_cat-parquet product_tag-parquet product_tag-wicanders first instock shipping-taxable product-type-simple\" id=\"id-5786\"  data-entry-id=\"5786\" >\n\t\t\t<div class=\"gs-product-item product-item--classic-grid\">\n\n\t        <div class=\"entry-thumbnail gs-product-thumbnail\">\n                            <div class=\"entry-image-ratio\" style=\"padding-bottom: 100.000000% !important;\">\n\t                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/caribbean-oak.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Parquet en ch\u00eane des Cara\u00efbes\" srcset=\"https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/caribbean-oak.jpg 1000w, https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/caribbean-oak-300x300.jpg 300w, https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/caribbean-oak-150x150.jpg 150w, https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/caribbean-oak-768x768.jpg 768w, https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/caribbean-oak-500x500.jpg 500w, https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/caribbean-oak-600x600.jpg 600w, https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/caribbean-oak-100x100.jpg 100w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                <\/div>\n                        <div class=\"product-buttons\">\n\t\t        <div class=\"product-buttons-inner\">\n\t\t\t        <a class=\"add_to_cart_button product_type_simple\" href=\"https:\/\/decormobel.com\/fr\/productos\/chene-des-caraibes\/\"><span class=\"gs-add-to-cart-btn\"><span>Lire la suite<\/span><\/span><\/a>\t\t\t        \t\t\t                        <\/div>\n            <\/div>\n                        <a href=\"https:\/\/decormobel.com\/fr\/productos\/chene-des-caraibes\/\" class=\"gs-product-link\"><\/a>\n        <\/div>\n\t\n    <div class=\"entry-details\">\n        <div class=\"entry-details__inner\">\n\t                        <h4 class=\"entry-details-title\"><a href=\"https:\/\/decormobel.com\/fr\/productos\/chene-des-caraibes\/\">CH\u00caNE DES CARA\u00cfBES<\/a><\/h4>\n\t                                    <div class=\"gs-product-cats\">\n                    <a href=\"https:\/\/decormobel.com\/fr\/categoria\/revetements\/parquet\/\" rel=\"tag\">Parquet<\/a>                <\/div>\n            \t                            <\/div>\n    <\/div>\n\n<\/div>\n\t\t<\/article>\n\t\t\t\t\t\t<article class=\"product-holder wow gsFadeIn post-5742 product type-product status-publish has-post-thumbnail product_cat-ceramica product_tag-ceramica product_tag-finfloor  instock shipping-taxable product-type-simple\" id=\"id-5742\"  data-entry-id=\"5742\" >\n\t\t\t<div class=\"gs-product-item product-item--classic-grid\">\n\n\t        <div class=\"entry-thumbnail gs-product-thumbnail\">\n                            <div class=\"entry-image-ratio\" style=\"padding-bottom: 100.000000% !important;\">\n\t                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/decormobel.com\/wp-content\/uploads\/2021\/10\/alfama-tile.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Rev\u00eatement en tuile Alfama\" srcset=\"https:\/\/decormobel.com\/wp-content\/uploads\/2021\/10\/alfama-tile.jpg 1000w, https:\/\/decormobel.com\/wp-content\/uploads\/2021\/10\/alfama-tile-300x300.jpg 300w, https:\/\/decormobel.com\/wp-content\/uploads\/2021\/10\/alfama-tile-150x150.jpg 150w, https:\/\/decormobel.com\/wp-content\/uploads\/2021\/10\/alfama-tile-768x768.jpg 768w, https:\/\/decormobel.com\/wp-content\/uploads\/2021\/10\/alfama-tile-500x500.jpg 500w, https:\/\/decormobel.com\/wp-content\/uploads\/2021\/10\/alfama-tile-600x600.jpg 600w, https:\/\/decormobel.com\/wp-content\/uploads\/2021\/10\/alfama-tile-100x100.jpg 100w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                <\/div>\n                        <div class=\"product-buttons\">\n\t\t        <div class=\"product-buttons-inner\">\n\t\t\t        <a class=\"add_to_cart_button product_type_simple\" href=\"https:\/\/decormobel.com\/fr\/productos\/tuile-alfama\/\"><span class=\"gs-add-to-cart-btn\"><span>Lire la suite<\/span><\/span><\/a>\t\t\t        \t\t\t                        <\/div>\n            <\/div>\n                        <a href=\"https:\/\/decormobel.com\/fr\/productos\/tuile-alfama\/\" class=\"gs-product-link\"><\/a>\n        <\/div>\n\t\n    <div class=\"entry-details\">\n        <div class=\"entry-details__inner\">\n\t                        <h4 class=\"entry-details-title\"><a href=\"https:\/\/decormobel.com\/fr\/productos\/tuile-alfama\/\">TUILE D&#039;ALFAMA<\/a><\/h4>\n\t                                    <div class=\"gs-product-cats\">\n                    <a href=\"https:\/\/decormobel.com\/fr\/categoria\/revetements\/ceramica\/\" rel=\"tag\">C\u00e9ramique<\/a>                <\/div>\n            \t                            <\/div>\n    <\/div>\n\n<\/div>\n\t\t<\/article>\n\t\t\t\t\t\t<article class=\"product-holder wow gsFadeIn post-5753 product type-product status-publish has-post-thumbnail product_cat-parquet product_tag-finfloor product_tag-parquet  instock shipping-taxable product-type-simple\" id=\"id-5753\"  data-entry-id=\"5753\" >\n\t\t\t<div class=\"gs-product-item product-item--classic-grid\">\n\n\t        <div class=\"entry-thumbnail gs-product-thumbnail\">\n                            <div class=\"entry-image-ratio\" style=\"padding-bottom: 100.000000% !important;\">\n\t                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/pino_fionia.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Parquet en pin Fyn\" srcset=\"https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/pino_fionia.jpg 1000w, https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/pino_fionia-300x300.jpg 300w, https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/pino_fionia-150x150.jpg 150w, https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/pino_fionia-768x768.jpg 768w, https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/pino_fionia-500x500.jpg 500w, https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/pino_fionia-600x600.jpg 600w, https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/pino_fionia-100x100.jpg 100w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                <\/div>\n                        <div class=\"product-buttons\">\n\t\t        <div class=\"product-buttons-inner\">\n\t\t\t        <a class=\"add_to_cart_button product_type_simple\" href=\"https:\/\/decormobel.com\/fr\/productos\/pin-fongique\/\"><span class=\"gs-add-to-cart-btn\"><span>Lire la suite<\/span><\/span><\/a>\t\t\t        \t\t\t                        <\/div>\n            <\/div>\n                        <a href=\"https:\/\/decormobel.com\/fr\/productos\/pin-fongique\/\" class=\"gs-product-link\"><\/a>\n        <\/div>\n\t\n    <div class=\"entry-details\">\n        <div class=\"entry-details__inner\">\n\t                        <h4 class=\"entry-details-title\"><a href=\"https:\/\/decormobel.com\/fr\/productos\/pin-fongique\/\">PIN DR\u00d4LE<\/a><\/h4>\n\t                                    <div class=\"gs-product-cats\">\n                    <a href=\"https:\/\/decormobel.com\/fr\/categoria\/revetements\/parquet\/\" rel=\"tag\">Parquet<\/a>                <\/div>\n            \t                            <\/div>\n    <\/div>\n\n<\/div>\n\t\t<\/article>\n\t\t\t\t\t\t<article class=\"product-holder wow gsFadeIn post-5763 product type-product status-publish has-post-thumbnail product_cat-parquet product_tag-finfloor product_tag-parquet last instock shipping-taxable product-type-simple\" id=\"id-5763\"  data-entry-id=\"5763\" >\n\t\t\t<div class=\"gs-product-item product-item--classic-grid\">\n\n\t        <div class=\"entry-thumbnail gs-product-thumbnail\">\n                            <div class=\"entry-image-ratio\" style=\"padding-bottom: 100.000000% !important;\">\n\t                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/roble_arles_natural.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Parquet ch\u00eane d&#039;arles naturel\" srcset=\"https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/roble_arles_natural.jpg 1000w, https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/roble_arles_natural-300x300.jpg 300w, https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/roble_arles_natural-150x150.jpg 150w, https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/roble_arles_natural-768x768.jpg 768w, https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/roble_arles_natural-500x500.jpg 500w, https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/roble_arles_natural-600x600.jpg 600w, https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/roble_arles_natural-100x100.jpg 100w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                <\/div>\n                        <div class=\"product-buttons\">\n\t\t        <div class=\"product-buttons-inner\">\n\t\t\t        <a class=\"add_to_cart_button product_type_simple\" href=\"https:\/\/decormobel.com\/fr\/productos\/chene-arles-naturel\/\"><span class=\"gs-add-to-cart-btn\"><span>Lire la suite<\/span><\/span><\/a>\t\t\t        \t\t\t                        <\/div>\n            <\/div>\n                        <a href=\"https:\/\/decormobel.com\/fr\/productos\/chene-arles-naturel\/\" class=\"gs-product-link\"><\/a>\n        <\/div>\n\t\n    <div class=\"entry-details\">\n        <div class=\"entry-details__inner\">\n\t                        <h4 class=\"entry-details-title\"><a href=\"https:\/\/decormobel.com\/fr\/productos\/chene-arles-naturel\/\">CH\u00caNE D&#039;ARLES NATUREL<\/a><\/h4>\n\t                                    <div class=\"gs-product-cats\">\n                    <a href=\"https:\/\/decormobel.com\/fr\/categoria\/revetements\/parquet\/\" rel=\"tag\">Parquet<\/a>                <\/div>\n            \t                            <\/div>\n    <\/div>\n\n<\/div>\n\t\t<\/article>\n\t\t\t\t\t\t<article class=\"product-holder wow gsFadeIn post-5767 product type-product status-publish has-post-thumbnail product_cat-parquet product_tag-finfloor product_tag-parquet first instock shipping-taxable product-type-simple\" id=\"id-5767\"  data-entry-id=\"5767\" >\n\t\t\t<div class=\"gs-product-item product-item--classic-grid\">\n\n\t        <div class=\"entry-thumbnail gs-product-thumbnail\">\n                            <div class=\"entry-image-ratio\" style=\"padding-bottom: 100.000000% !important;\">\n\t                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/roble_arles_oscuro.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Parquet ch\u00eane d&#039;arles fonc\u00e9\" srcset=\"https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/roble_arles_oscuro.jpg 1000w, https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/roble_arles_oscuro-300x300.jpg 300w, https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/roble_arles_oscuro-150x150.jpg 150w, https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/roble_arles_oscuro-768x768.jpg 768w, https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/roble_arles_oscuro-500x500.jpg 500w, https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/roble_arles_oscuro-600x600.jpg 600w, https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/roble_arles_oscuro-100x100.jpg 100w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                <\/div>\n                        <div class=\"product-buttons\">\n\t\t        <div class=\"product-buttons-inner\">\n\t\t\t        <a class=\"add_to_cart_button product_type_simple\" href=\"https:\/\/decormobel.com\/fr\/productos\/chene-arles-fonce\/\"><span class=\"gs-add-to-cart-btn\"><span>Lire la suite<\/span><\/span><\/a>\t\t\t        \t\t\t                        <\/div>\n            <\/div>\n                        <a href=\"https:\/\/decormobel.com\/fr\/productos\/chene-arles-fonce\/\" class=\"gs-product-link\"><\/a>\n        <\/div>\n\t\n    <div class=\"entry-details\">\n        <div class=\"entry-details__inner\">\n\t                        <h4 class=\"entry-details-title\"><a href=\"https:\/\/decormobel.com\/fr\/productos\/chene-arles-fonce\/\">CH\u00caNE D&#039;ARLES FONC\u00c9<\/a><\/h4>\n\t                                    <div class=\"gs-product-cats\">\n                    <a href=\"https:\/\/decormobel.com\/fr\/categoria\/revetements\/parquet\/\" rel=\"tag\">Parquet<\/a>                <\/div>\n            \t                            <\/div>\n    <\/div>\n\n<\/div>\n\t\t<\/article>\n\t\t\t\t\t\t<article class=\"product-holder wow gsFadeIn post-5772 product type-product status-publish has-post-thumbnail product_cat-parquet product_tag-finfloor product_tag-parquet  instock shipping-taxable product-type-simple\" id=\"id-5772\"  data-entry-id=\"5772\" >\n\t\t\t<div class=\"gs-product-item product-item--classic-grid\">\n\n\t        <div class=\"entry-thumbnail gs-product-thumbnail\">\n                            <div class=\"entry-image-ratio\" style=\"padding-bottom: 100.000000% !important;\">\n\t                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/roble_kalmar_blanco.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Parquet Ch\u00eane Kalmar Blanc\" srcset=\"https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/roble_kalmar_blanco.jpg 1000w, https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/roble_kalmar_blanco-300x300.jpg 300w, https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/roble_kalmar_blanco-150x150.jpg 150w, https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/roble_kalmar_blanco-768x768.jpg 768w, https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/roble_kalmar_blanco-500x500.jpg 500w, https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/roble_kalmar_blanco-600x600.jpg 600w, https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/roble_kalmar_blanco-100x100.jpg 100w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                <\/div>\n                        <div class=\"product-buttons\">\n\t\t        <div class=\"product-buttons-inner\">\n\t\t\t        <a class=\"add_to_cart_button product_type_simple\" href=\"https:\/\/decormobel.com\/fr\/productos\/chene-kalmar-blanc\/\"><span class=\"gs-add-to-cart-btn\"><span>Lire la suite<\/span><\/span><\/a>\t\t\t        \t\t\t                        <\/div>\n            <\/div>\n                        <a href=\"https:\/\/decormobel.com\/fr\/productos\/chene-kalmar-blanc\/\" class=\"gs-product-link\"><\/a>\n        <\/div>\n\t\n    <div class=\"entry-details\">\n        <div class=\"entry-details__inner\">\n\t                        <h4 class=\"entry-details-title\"><a href=\"https:\/\/decormobel.com\/fr\/productos\/chene-kalmar-blanc\/\">CH\u00caNE KALMAR BLANC<\/a><\/h4>\n\t                                    <div class=\"gs-product-cats\">\n                    <a href=\"https:\/\/decormobel.com\/fr\/categoria\/revetements\/parquet\/\" rel=\"tag\">Parquet<\/a>                <\/div>\n            \t                            <\/div>\n    <\/div>\n\n<\/div>\n\t\t<\/article>\n\t\t\t\t\t\t<article class=\"product-holder wow gsFadeIn post-5777 product type-product status-publish has-post-thumbnail product_cat-parquet product_tag-finfloor product_tag-parquet  instock shipping-taxable product-type-simple\" id=\"id-5777\"  data-entry-id=\"5777\" >\n\t\t\t<div class=\"gs-product-item product-item--classic-grid\">\n\n\t        <div class=\"entry-thumbnail gs-product-thumbnail\">\n                            <div class=\"entry-image-ratio\" style=\"padding-bottom: 100.000000% !important;\">\n\t                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/roble_kalmar_gris.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Parquet ch\u00eane kalmar gris\" srcset=\"https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/roble_kalmar_gris.jpg 1000w, https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/roble_kalmar_gris-300x300.jpg 300w, https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/roble_kalmar_gris-150x150.jpg 150w, https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/roble_kalmar_gris-768x768.jpg 768w, https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/roble_kalmar_gris-500x500.jpg 500w, https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/roble_kalmar_gris-600x600.jpg 600w, https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/roble_kalmar_gris-100x100.jpg 100w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                <\/div>\n                        <div class=\"product-buttons\">\n\t\t        <div class=\"product-buttons-inner\">\n\t\t\t        <a class=\"add_to_cart_button product_type_simple\" href=\"https:\/\/decormobel.com\/fr\/productos\/chene-kalmar-gris\/\"><span class=\"gs-add-to-cart-btn\"><span>Lire la suite<\/span><\/span><\/a>\t\t\t        \t\t\t                        <\/div>\n            <\/div>\n                        <a href=\"https:\/\/decormobel.com\/fr\/productos\/chene-kalmar-gris\/\" class=\"gs-product-link\"><\/a>\n        <\/div>\n\t\n    <div class=\"entry-details\">\n        <div class=\"entry-details__inner\">\n\t                        <h4 class=\"entry-details-title\"><a href=\"https:\/\/decormobel.com\/fr\/productos\/chene-kalmar-gris\/\">CH\u00caNE KALMAR GRIS<\/a><\/h4>\n\t                                    <div class=\"gs-product-cats\">\n                    <a href=\"https:\/\/decormobel.com\/fr\/categoria\/revetements\/parquet\/\" rel=\"tag\">Parquet<\/a>                <\/div>\n            \t                            <\/div>\n    <\/div>\n\n<\/div>\n\t\t<\/article>\n\t\t\t\t\t\t<article class=\"product-holder wow gsFadeIn post-5782 product type-product status-publish has-post-thumbnail product_cat-parquet product_tag-parquet product_tag-wicanders last instock shipping-taxable product-type-simple\" id=\"id-5782\"  data-entry-id=\"5782\" >\n\t\t\t<div class=\"gs-product-item product-item--classic-grid\">\n\n\t        <div class=\"entry-thumbnail gs-product-thumbnail\">\n                            <div class=\"entry-image-ratio\" style=\"padding-bottom: 100.000000% !important;\">\n\t                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/alaska-oak.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"ch\u00eane d&#039;Alaska\" srcset=\"https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/alaska-oak.jpg 1000w, https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/alaska-oak-300x300.jpg 300w, https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/alaska-oak-150x150.jpg 150w, https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/alaska-oak-768x768.jpg 768w, https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/alaska-oak-500x500.jpg 500w, https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/alaska-oak-600x600.jpg 600w, https:\/\/decormobel.com\/wp-content\/uploads\/2022\/04\/alaska-oak-100x100.jpg 100w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                <\/div>\n                        <div class=\"product-buttons\">\n\t\t        <div class=\"product-buttons-inner\">\n\t\t\t        <a class=\"add_to_cart_button product_type_simple\" href=\"https:\/\/decormobel.com\/fr\/productos\/chene-dalaska\/\"><span class=\"gs-add-to-cart-btn\"><span>Lire la suite<\/span><\/span><\/a>\t\t\t        \t\t\t                        <\/div>\n            <\/div>\n                        <a href=\"https:\/\/decormobel.com\/fr\/productos\/chene-dalaska\/\" class=\"gs-product-link\"><\/a>\n        <\/div>\n\t\n    <div class=\"entry-details\">\n        <div class=\"entry-details__inner\">\n\t                        <h4 class=\"entry-details-title\"><a href=\"https:\/\/decormobel.com\/fr\/productos\/chene-dalaska\/\">CH\u00caNE D&#039;ALASKA<\/a><\/h4>\n\t                                    <div class=\"gs-product-cats\">\n                    <a href=\"https:\/\/decormobel.com\/fr\/categoria\/revetements\/parquet\/\" rel=\"tag\">Parquet<\/a>                <\/div>\n            \t                            <\/div>\n    <\/div>\n\n<\/div>\n\t\t<\/article>\n\t\t\n<\/div>\n<script type=\"text\/javascript\">\n    jQuery(function ($) {\n        var owl = $('#gs-shop-carousel-6a04500960a6d');\n\n        owl.owlCarousel({\n            items: 1,\n            margin: 0,\n            autoHeight: true,\n            loop: true,\n            mouseDrag: true,\n            touchDrag: true,\n            stagePadding: 0,\n            startPosition: 0,\n            nav: true,\n            navText: [\n                '<svg width=\"20\" height=\"20\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M19 12H5\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/><path d=\"M12 19L5 12L12 5\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/><\/svg>',\n                '<svg width=\"20\" height=\"20\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M5 12H19\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/><path d=\"M12 5L19 12L12 19\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/><\/svg>',\n            ],\n            dots: false,\n            autoplay: true,\n            autoplayTimeout: 2000,\n            autoplayHoverPause: false,\n            smartSpeed: 450,\n            responsive:{\n                768:{\n                    items: 2,\n                    margin: 0,\n                    stagePadding: 0                },\n                992:{\n                    items: 4,\n                    margin: 0,\n                    stagePadding: 0                }\n            }\n        });\n    });\n<\/script>                <\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Parquets et c\u00e9ramiques Des sols pour tous les go\u00fbts Parquets naturels, synth\u00e9tiques de haute qualit\u00e9, c\u00e9ramiques et gr\u00e8s. Quoi que vous imaginiez, nous pouvons r\u00e9aliser\u2026.<\/p>","protected":false},"author":1,"featured_media":0,"parent":825,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"class_list":["post-3791","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/decormobel.com\/fr\/wp-json\/wp\/v2\/pages\/3791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/decormobel.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/decormobel.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/decormobel.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/decormobel.com\/fr\/wp-json\/wp\/v2\/comments?post=3791"}],"version-history":[{"count":53,"href":"https:\/\/decormobel.com\/fr\/wp-json\/wp\/v2\/pages\/3791\/revisions"}],"predecessor-version":[{"id":8056,"href":"https:\/\/decormobel.com\/fr\/wp-json\/wp\/v2\/pages\/3791\/revisions\/8056"}],"up":[{"embeddable":true,"href":"https:\/\/decormobel.com\/fr\/wp-json\/wp\/v2\/pages\/825"}],"wp:attachment":[{"href":"https:\/\/decormobel.com\/fr\/wp-json\/wp\/v2\/media?parent=3791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}